{"id":2565,"date":"2024-07-30T11:41:14","date_gmt":"2024-07-30T11:41:14","guid":{"rendered":"https:\/\/argest.lu\/services\/construction-and-building-management"},"modified":"2025-12-09T14:24:41","modified_gmt":"2025-12-09T14:24:41","slug":"construction-and-building-management","status":"publish","type":"services","link":"https:\/\/argest.lu\/en\/services\/construction-and-building-management","title":{"rendered":"Construction and Building Management"},"template":"","class_list":["post-2565","services","type-services","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Argest<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:site_name\" content=\"Argest\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":null,\"url\":\"\",\"name\":\"\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.argest.lu\\\/en#website\"},\"inLanguage\":\"en-US\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.argest.lu\\\/en#website\",\"url\":\"https:\\\/\\\/www.argest.lu\\\/en\",\"name\":\"Argest\",\"description\":\"bureau d\u2019\u00e9tudes ind\u00e9pendant, membre de l\u2019Ordre des Architectes et des Ing\u00e9nieurs-conseils du Grand-Duch\u00e9 de Luxembourg\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.argest.lu\\\/en#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.argest.lu\\\/en?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.argest.lu\\\/en#organization\",\"name\":\"Argest\",\"url\":\"https:\\\/\\\/www.argest.lu\\\/en\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.argest.lu\\\/en#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/argest.lu\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/argest.jpg\",\"contentUrl\":\"https:\\\/\\\/argest.lu\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/argest.jpg\",\"width\":769,\"height\":945,\"caption\":\"Argest\"},\"image\":{\"@id\":\"https:\\\/\\\/www.argest.lu\\\/en#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Argest","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"\/","og_locale":"en_US","og_type":"article","og_site_name":"Argest","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":null,"url":"","name":"","isPartOf":{"@id":"https:\/\/www.argest.lu\/en#website"},"inLanguage":"en-US"},{"@type":"WebSite","@id":"https:\/\/www.argest.lu\/en#website","url":"https:\/\/www.argest.lu\/en","name":"Argest","description":"bureau d\u2019\u00e9tudes ind\u00e9pendant, membre de l\u2019Ordre des Architectes et des Ing\u00e9nieurs-conseils du Grand-Duch\u00e9 de Luxembourg","publisher":{"@id":"https:\/\/www.argest.lu\/en#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.argest.lu\/en?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.argest.lu\/en#organization","name":"Argest","url":"https:\/\/www.argest.lu\/en","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.argest.lu\/en#\/schema\/logo\/image\/","url":"https:\/\/argest.lu\/wp-content\/uploads\/2024\/02\/argest.jpg","contentUrl":"https:\/\/argest.lu\/wp-content\/uploads\/2024\/02\/argest.jpg","width":769,"height":945,"caption":"Argest"},"image":{"@id":"https:\/\/www.argest.lu\/en#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/argest.lu\/en\/wp-json\/wp\/v2\/services\/2565"}],"collection":[{"href":"https:\/\/argest.lu\/en\/wp-json\/wp\/v2\/services"}],"about":[{"href":"https:\/\/argest.lu\/en\/wp-json\/wp\/v2\/types\/services"}],"wp:attachment":[{"href":"https:\/\/argest.lu\/en\/wp-json\/wp\/v2\/media?parent=2565"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}