{"id":2604,"date":"2024-10-07T05:30:46","date_gmt":"2024-10-07T05:30:46","guid":{"rendered":"https:\/\/argest.lu\/reference\/optimierung-des-sicherheitsmanagements-der-dienste-der-gemeinde-tandel"},"modified":"2025-08-06T09:46:41","modified_gmt":"2025-08-06T09:46:41","slug":"optimierung-des-sicherheitsmanagements-der-dienste-der-gemeinde-tandel","status":"publish","type":"reference","link":"https:\/\/argest.lu\/de\/reference\/optimierung-des-sicherheitsmanagements-der-dienste-der-gemeinde-tandel","title":{"rendered":"Optimierung des Sicherheitsmanagements der Dienste der Gemeinde Tandel"},"content":{"rendered":"\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:20%\">\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" width=\"120\" height=\"170\" data-src=\"http:\/\/argest.lu\/wp-content\/uploads\/2024\/10\/2-1-1.png\" alt=\"\" class=\"wp-image-1551 lazyload\" style=\"--smush-placeholder-width: 120px; --smush-placeholder-aspect-ratio: 120\/170;width:129px;height:auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:80%\">\n<p>Tandel ist eine der Gemeinden, die sich f\u00fcr ARGEST S.A. entschieden haben, um sie bei der Optimierung des Sicherheitsmanagements ihrer Dienste zu unterst\u00fctzen.<\/p>\n\n\n\n<p>ARGEST S.A. mit seinen verschiedenen Kompetenzen unterst\u00fctzt die Gemeinde in :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>  die Verbesserung der BCM- und ISO 45001-Managementprozesse<\/li>\n\n\n\n<li>die Durchf\u00fchrung von Zug\u00e4nglichkeitspr\u00fcfungen f\u00fcr Menschen mit Behinderungen<\/li>\n\n\n\n<li>die Verbesserung der Sicherheit und Gesundheit seiner Mitarbeiter und aller Bewohner der von der Gemeinde verwalteten Geb\u00e4ude<\/li>\n<\/ul>\n\n\n\n<p>Unser kooperativer Ansatz, der auf die Bed\u00fcrfnisse der Gemeindeverwaltungen zugeschnitten ist, f\u00fcgt sich nahtlos in den Ansatz der resilienten Gemeinden in Luxemburg ein.<\/p>\n<\/div>\n<\/div>\n","protected":false},"featured_media":1574,"template":"","class_list":["post-2604","reference","type-reference","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Optimierung des Sicherheitsmanagements der Dienste der Gemeinde Tandel - Argest<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/argest.lu\/de\/reference\/optimierung-des-sicherheitsmanagements-der-dienste-der-gemeinde-tandel\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Optimierung des Sicherheitsmanagements der Dienste der Gemeinde Tandel - Argest\" \/>\n<meta property=\"og:description\" content=\"Tandel ist eine der Gemeinden, die sich f\u00fcr ARGEST S.A. entschieden haben, um sie bei der Optimierung des Sicherheitsmanagements ihrer Dienste zu unterst\u00fctzen. ARGEST S.A. mit seinen verschiedenen Kompetenzen unterst\u00fctzt die Gemeinde in : Unser kooperativer Ansatz, der auf die Bed\u00fcrfnisse der Gemeindeverwaltungen zugeschnitten ist, f\u00fcgt sich nahtlos in den Ansatz der resilienten Gemeinden in [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/argest.lu\/de\/reference\/optimierung-des-sicherheitsmanagements-der-dienste-der-gemeinde-tandel\" \/>\n<meta property=\"og:site_name\" content=\"Argest\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-06T09:46:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/argest.lu\/wp-content\/uploads\/2024\/10\/tandel.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1924\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/argest.lu\\\/de\\\/reference\\\/optimierung-des-sicherheitsmanagements-der-dienste-der-gemeinde-tandel\",\"url\":\"https:\\\/\\\/argest.lu\\\/de\\\/reference\\\/optimierung-des-sicherheitsmanagements-der-dienste-der-gemeinde-tandel\",\"name\":\"Optimierung des Sicherheitsmanagements der Dienste der Gemeinde Tandel - Argest\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.argest.lu\\\/de#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/argest.lu\\\/de\\\/reference\\\/optimierung-des-sicherheitsmanagements-der-dienste-der-gemeinde-tandel#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/argest.lu\\\/de\\\/reference\\\/optimierung-des-sicherheitsmanagements-der-dienste-der-gemeinde-tandel#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/argest.lu\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/tandel.jpg\",\"datePublished\":\"2024-10-07T05:30:46+00:00\",\"dateModified\":\"2025-08-06T09:46:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/argest.lu\\\/de\\\/reference\\\/optimierung-des-sicherheitsmanagements-der-dienste-der-gemeinde-tandel#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/argest.lu\\\/de\\\/reference\\\/optimierung-des-sicherheitsmanagements-der-dienste-der-gemeinde-tandel\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/argest.lu\\\/de\\\/reference\\\/optimierung-des-sicherheitsmanagements-der-dienste-der-gemeinde-tandel#primaryimage\",\"url\":\"https:\\\/\\\/argest.lu\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/tandel.jpg\",\"contentUrl\":\"https:\\\/\\\/argest.lu\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/tandel.jpg\",\"width\":1924,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/argest.lu\\\/de\\\/reference\\\/optimierung-des-sicherheitsmanagements-der-dienste-der-gemeinde-tandel#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/argest.lu\\\/de\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00e9f\u00e9rence\",\"item\":\"https:\\\/\\\/argest.lu\\\/de\\\/reference\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Optimierung des Sicherheitsmanagements der Dienste der Gemeinde Tandel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.argest.lu\\\/de#website\",\"url\":\"https:\\\/\\\/www.argest.lu\\\/de\",\"name\":\"Argest\",\"description\":\"bureau d\u2019\u00e9tudes ind\u00e9pendant, membre de l\u2019Ordre des Architectes et des Ing\u00e9nieurs-conseils du Grand-Duch\u00e9 de Luxembourg\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.argest.lu\\\/de#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.argest.lu\\\/de?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.argest.lu\\\/de#organization\",\"name\":\"Argest\",\"url\":\"https:\\\/\\\/www.argest.lu\\\/de\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.argest.lu\\\/de#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/argest.lu\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/argest.jpg\",\"contentUrl\":\"https:\\\/\\\/argest.lu\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/argest.jpg\",\"width\":769,\"height\":945,\"caption\":\"Argest\"},\"image\":{\"@id\":\"https:\\\/\\\/www.argest.lu\\\/de#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Optimierung des Sicherheitsmanagements der Dienste der Gemeinde Tandel - Argest","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/argest.lu\/de\/reference\/optimierung-des-sicherheitsmanagements-der-dienste-der-gemeinde-tandel","og_locale":"de_DE","og_type":"article","og_title":"Optimierung des Sicherheitsmanagements der Dienste der Gemeinde Tandel - Argest","og_description":"Tandel ist eine der Gemeinden, die sich f\u00fcr ARGEST S.A. entschieden haben, um sie bei der Optimierung des Sicherheitsmanagements ihrer Dienste zu unterst\u00fctzen. ARGEST S.A. mit seinen verschiedenen Kompetenzen unterst\u00fctzt die Gemeinde in : Unser kooperativer Ansatz, der auf die Bed\u00fcrfnisse der Gemeindeverwaltungen zugeschnitten ist, f\u00fcgt sich nahtlos in den Ansatz der resilienten Gemeinden in [&hellip;]","og_url":"https:\/\/argest.lu\/de\/reference\/optimierung-des-sicherheitsmanagements-der-dienste-der-gemeinde-tandel","og_site_name":"Argest","article_modified_time":"2025-08-06T09:46:41+00:00","og_image":[{"width":1924,"height":1080,"url":"https:\/\/argest.lu\/wp-content\/uploads\/2024\/10\/tandel.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/argest.lu\/de\/reference\/optimierung-des-sicherheitsmanagements-der-dienste-der-gemeinde-tandel","url":"https:\/\/argest.lu\/de\/reference\/optimierung-des-sicherheitsmanagements-der-dienste-der-gemeinde-tandel","name":"Optimierung des Sicherheitsmanagements der Dienste der Gemeinde Tandel - Argest","isPartOf":{"@id":"https:\/\/www.argest.lu\/de#website"},"primaryImageOfPage":{"@id":"https:\/\/argest.lu\/de\/reference\/optimierung-des-sicherheitsmanagements-der-dienste-der-gemeinde-tandel#primaryimage"},"image":{"@id":"https:\/\/argest.lu\/de\/reference\/optimierung-des-sicherheitsmanagements-der-dienste-der-gemeinde-tandel#primaryimage"},"thumbnailUrl":"https:\/\/argest.lu\/wp-content\/uploads\/2024\/10\/tandel.jpg","datePublished":"2024-10-07T05:30:46+00:00","dateModified":"2025-08-06T09:46:41+00:00","breadcrumb":{"@id":"https:\/\/argest.lu\/de\/reference\/optimierung-des-sicherheitsmanagements-der-dienste-der-gemeinde-tandel#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/argest.lu\/de\/reference\/optimierung-des-sicherheitsmanagements-der-dienste-der-gemeinde-tandel"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/argest.lu\/de\/reference\/optimierung-des-sicherheitsmanagements-der-dienste-der-gemeinde-tandel#primaryimage","url":"https:\/\/argest.lu\/wp-content\/uploads\/2024\/10\/tandel.jpg","contentUrl":"https:\/\/argest.lu\/wp-content\/uploads\/2024\/10\/tandel.jpg","width":1924,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/argest.lu\/de\/reference\/optimierung-des-sicherheitsmanagements-der-dienste-der-gemeinde-tandel#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/argest.lu\/de"},{"@type":"ListItem","position":2,"name":"R\u00e9f\u00e9rence","item":"https:\/\/argest.lu\/de\/reference"},{"@type":"ListItem","position":3,"name":"Optimierung des Sicherheitsmanagements der Dienste der Gemeinde Tandel"}]},{"@type":"WebSite","@id":"https:\/\/www.argest.lu\/de#website","url":"https:\/\/www.argest.lu\/de","name":"Argest","description":"bureau d\u2019\u00e9tudes ind\u00e9pendant, membre de l\u2019Ordre des Architectes et des Ing\u00e9nieurs-conseils du Grand-Duch\u00e9 de Luxembourg","publisher":{"@id":"https:\/\/www.argest.lu\/de#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.argest.lu\/de?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.argest.lu\/de#organization","name":"Argest","url":"https:\/\/www.argest.lu\/de","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.argest.lu\/de#\/schema\/logo\/image\/","url":"https:\/\/argest.lu\/wp-content\/uploads\/2024\/02\/argest.jpg","contentUrl":"https:\/\/argest.lu\/wp-content\/uploads\/2024\/02\/argest.jpg","width":769,"height":945,"caption":"Argest"},"image":{"@id":"https:\/\/www.argest.lu\/de#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/argest.lu\/de\/wp-json\/wp\/v2\/reference\/2604","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/argest.lu\/de\/wp-json\/wp\/v2\/reference"}],"about":[{"href":"https:\/\/argest.lu\/de\/wp-json\/wp\/v2\/types\/reference"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/argest.lu\/de\/wp-json\/wp\/v2\/media\/1574"}],"wp:attachment":[{"href":"https:\/\/argest.lu\/de\/wp-json\/wp\/v2\/media?parent=2604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}