{"id":2484,"date":"2021-08-01T06:29:00","date_gmt":"2021-08-01T06:29:00","guid":{"rendered":"https:\/\/argest.lu\/bau-der-neuen-kindertagesstaette-in-gasperich"},"modified":"2025-08-06T09:46:20","modified_gmt":"2025-08-06T09:46:20","slug":"bau-der-neuen-kindertagesstaette-in-gasperich","status":"publish","type":"post","link":"https:\/\/argest.lu\/de\/bau-der-neuen-kindertagesstaette-in-gasperich","title":{"rendered":"Bau der neuen Kindertagesst\u00e4tte in Gasperich"},"content":{"rendered":"\n<p>ARGEST wurde f\u00fcr dieses Projekt beauftragt, die Sicherheits- und Gesundheitskoordination zu \u00fcbernehmen. In der Ausgabe 03-2021 von B2LUX finden Sie einen Artikel \u00fcber dieses Projekt. (auf Deutsch) <a href=\"https:\/\/argest.lu\/\/app\/uploads\/2021\/08\/B2LUX_32021_Argest.pdf\">Link zum Artikel<\/a> <a href=\"https:\/\/issuu.com\/medienhaus_luxembourg\/docs\/b2lux_3_2021\">Link zur Ausgabe B2LUX 3-2021<\/a>  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>ARGEST wurde f\u00fcr dieses Projekt beauftragt, die Sicherheits- und Gesundheitskoordination zu \u00fcbernehmen. In der Ausgabe 03-2021 von B2LUX finden Sie einen Artikel \u00fcber dieses Projekt. (auf Deutsch) Link zum Artikel Link zur Ausgabe B2LUX 3-2021<\/p>\n","protected":false},"author":1,"featured_media":1124,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"class_list":["post-2484","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-unkategorisiert"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bau der neuen Kindertagesst\u00e4tte in Gasperich - Argest<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/argest.lu\/de\/bau-der-neuen-kindertagesstaette-in-gasperich\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bau der neuen Kindertagesst\u00e4tte in Gasperich - Argest\" \/>\n<meta property=\"og:description\" content=\"ARGEST wurde f\u00fcr dieses Projekt beauftragt, die Sicherheits- und Gesundheitskoordination zu \u00fcbernehmen. In der Ausgabe 03-2021 von B2LUX finden Sie einen Artikel \u00fcber dieses Projekt. (auf Deutsch) Link zum Artikel Link zur Ausgabe B2LUX 3-2021\" \/>\n<meta property=\"og:url\" content=\"https:\/\/argest.lu\/de\/bau-der-neuen-kindertagesstaette-in-gasperich\" \/>\n<meta property=\"og:site_name\" content=\"Argest\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-01T06:29:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-06T09:46:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/argest.lu\/wp-content\/uploads\/2024\/02\/Creche-Gasperich.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"508\" \/>\n\t<meta property=\"og:image:height\" content=\"406\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"hamitso\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"hamitso\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/argest.lu\\\/de\\\/bau-der-neuen-kindertagesstaette-in-gasperich#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/argest.lu\\\/de\\\/bau-der-neuen-kindertagesstaette-in-gasperich\"},\"author\":{\"name\":\"hamitso\",\"@id\":\"https:\\\/\\\/www.argest.lu\\\/de#\\\/schema\\\/person\\\/8b7b6c7808b0df3e7c1da4e4c9ff509b\"},\"headline\":\"Bau der neuen Kindertagesst\u00e4tte in Gasperich\",\"datePublished\":\"2021-08-01T06:29:00+00:00\",\"dateModified\":\"2025-08-06T09:46:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/argest.lu\\\/de\\\/bau-der-neuen-kindertagesstaette-in-gasperich\"},\"wordCount\":45,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.argest.lu\\\/de#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/argest.lu\\\/de\\\/bau-der-neuen-kindertagesstaette-in-gasperich#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/argest.lu\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Creche-Gasperich.jpg\",\"articleSection\":[\"Unkategorisiert\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/argest.lu\\\/de\\\/bau-der-neuen-kindertagesstaette-in-gasperich\",\"url\":\"https:\\\/\\\/argest.lu\\\/de\\\/bau-der-neuen-kindertagesstaette-in-gasperich\",\"name\":\"Bau der neuen Kindertagesst\u00e4tte in Gasperich - Argest\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.argest.lu\\\/de#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/argest.lu\\\/de\\\/bau-der-neuen-kindertagesstaette-in-gasperich#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/argest.lu\\\/de\\\/bau-der-neuen-kindertagesstaette-in-gasperich#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/argest.lu\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Creche-Gasperich.jpg\",\"datePublished\":\"2021-08-01T06:29:00+00:00\",\"dateModified\":\"2025-08-06T09:46:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/argest.lu\\\/de\\\/bau-der-neuen-kindertagesstaette-in-gasperich#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/argest.lu\\\/de\\\/bau-der-neuen-kindertagesstaette-in-gasperich\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/argest.lu\\\/de\\\/bau-der-neuen-kindertagesstaette-in-gasperich#primaryimage\",\"url\":\"https:\\\/\\\/argest.lu\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Creche-Gasperich.jpg\",\"contentUrl\":\"https:\\\/\\\/argest.lu\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Creche-Gasperich.jpg\",\"width\":508,\"height\":406},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/argest.lu\\\/de\\\/bau-der-neuen-kindertagesstaette-in-gasperich#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/argest.lu\\\/de\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bau der neuen Kindertagesst\u00e4tte in Gasperich\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.argest.lu\\\/de#website\",\"url\":\"https:\\\/\\\/www.argest.lu\\\/de\",\"name\":\"Argest\",\"description\":\"bureau d\u2019\u00e9tudes ind\u00e9pendant, membre de l\u2019Ordre des Architectes et des Ing\u00e9nieurs-conseils du Grand-Duch\u00e9 de Luxembourg\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.argest.lu\\\/de#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.argest.lu\\\/de?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.argest.lu\\\/de#organization\",\"name\":\"Argest\",\"url\":\"https:\\\/\\\/www.argest.lu\\\/de\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.argest.lu\\\/de#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/argest.lu\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/argest.jpg\",\"contentUrl\":\"https:\\\/\\\/argest.lu\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/argest.jpg\",\"width\":769,\"height\":945,\"caption\":\"Argest\"},\"image\":{\"@id\":\"https:\\\/\\\/www.argest.lu\\\/de#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.argest.lu\\\/de#\\\/schema\\\/person\\\/8b7b6c7808b0df3e7c1da4e4c9ff509b\",\"name\":\"hamitso\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b0d2b34ed9cec25863f37f628f3780ef6de1b759e8dbbbd7c855ba95d576f3bd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b0d2b34ed9cec25863f37f628f3780ef6de1b759e8dbbbd7c855ba95d576f3bd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b0d2b34ed9cec25863f37f628f3780ef6de1b759e8dbbbd7c855ba95d576f3bd?s=96&d=mm&r=g\",\"caption\":\"hamitso\"},\"sameAs\":[\"https:\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bau der neuen Kindertagesst\u00e4tte in Gasperich - Argest","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/argest.lu\/de\/bau-der-neuen-kindertagesstaette-in-gasperich","og_locale":"de_DE","og_type":"article","og_title":"Bau der neuen Kindertagesst\u00e4tte in Gasperich - Argest","og_description":"ARGEST wurde f\u00fcr dieses Projekt beauftragt, die Sicherheits- und Gesundheitskoordination zu \u00fcbernehmen. In der Ausgabe 03-2021 von B2LUX finden Sie einen Artikel \u00fcber dieses Projekt. (auf Deutsch) Link zum Artikel Link zur Ausgabe B2LUX 3-2021","og_url":"https:\/\/argest.lu\/de\/bau-der-neuen-kindertagesstaette-in-gasperich","og_site_name":"Argest","article_published_time":"2021-08-01T06:29:00+00:00","article_modified_time":"2025-08-06T09:46:20+00:00","og_image":[{"width":508,"height":406,"url":"https:\/\/argest.lu\/wp-content\/uploads\/2024\/02\/Creche-Gasperich.jpg","type":"image\/jpeg"}],"author":"hamitso","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"hamitso"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/argest.lu\/de\/bau-der-neuen-kindertagesstaette-in-gasperich#article","isPartOf":{"@id":"https:\/\/argest.lu\/de\/bau-der-neuen-kindertagesstaette-in-gasperich"},"author":{"name":"hamitso","@id":"https:\/\/www.argest.lu\/de#\/schema\/person\/8b7b6c7808b0df3e7c1da4e4c9ff509b"},"headline":"Bau der neuen Kindertagesst\u00e4tte in Gasperich","datePublished":"2021-08-01T06:29:00+00:00","dateModified":"2025-08-06T09:46:20+00:00","mainEntityOfPage":{"@id":"https:\/\/argest.lu\/de\/bau-der-neuen-kindertagesstaette-in-gasperich"},"wordCount":45,"commentCount":0,"publisher":{"@id":"https:\/\/www.argest.lu\/de#organization"},"image":{"@id":"https:\/\/argest.lu\/de\/bau-der-neuen-kindertagesstaette-in-gasperich#primaryimage"},"thumbnailUrl":"https:\/\/argest.lu\/wp-content\/uploads\/2024\/02\/Creche-Gasperich.jpg","articleSection":["Unkategorisiert"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/argest.lu\/de\/bau-der-neuen-kindertagesstaette-in-gasperich","url":"https:\/\/argest.lu\/de\/bau-der-neuen-kindertagesstaette-in-gasperich","name":"Bau der neuen Kindertagesst\u00e4tte in Gasperich - Argest","isPartOf":{"@id":"https:\/\/www.argest.lu\/de#website"},"primaryImageOfPage":{"@id":"https:\/\/argest.lu\/de\/bau-der-neuen-kindertagesstaette-in-gasperich#primaryimage"},"image":{"@id":"https:\/\/argest.lu\/de\/bau-der-neuen-kindertagesstaette-in-gasperich#primaryimage"},"thumbnailUrl":"https:\/\/argest.lu\/wp-content\/uploads\/2024\/02\/Creche-Gasperich.jpg","datePublished":"2021-08-01T06:29:00+00:00","dateModified":"2025-08-06T09:46:20+00:00","breadcrumb":{"@id":"https:\/\/argest.lu\/de\/bau-der-neuen-kindertagesstaette-in-gasperich#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/argest.lu\/de\/bau-der-neuen-kindertagesstaette-in-gasperich"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/argest.lu\/de\/bau-der-neuen-kindertagesstaette-in-gasperich#primaryimage","url":"https:\/\/argest.lu\/wp-content\/uploads\/2024\/02\/Creche-Gasperich.jpg","contentUrl":"https:\/\/argest.lu\/wp-content\/uploads\/2024\/02\/Creche-Gasperich.jpg","width":508,"height":406},{"@type":"BreadcrumbList","@id":"https:\/\/argest.lu\/de\/bau-der-neuen-kindertagesstaette-in-gasperich#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/argest.lu\/de"},{"@type":"ListItem","position":2,"name":"Bau der neuen Kindertagesst\u00e4tte in Gasperich"}]},{"@type":"WebSite","@id":"https:\/\/www.argest.lu\/de#website","url":"https:\/\/www.argest.lu\/de","name":"Argest","description":"bureau d\u2019\u00e9tudes ind\u00e9pendant, membre de l\u2019Ordre des Architectes et des Ing\u00e9nieurs-conseils du Grand-Duch\u00e9 de Luxembourg","publisher":{"@id":"https:\/\/www.argest.lu\/de#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.argest.lu\/de?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.argest.lu\/de#organization","name":"Argest","url":"https:\/\/www.argest.lu\/de","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.argest.lu\/de#\/schema\/logo\/image\/","url":"https:\/\/argest.lu\/wp-content\/uploads\/2024\/02\/argest.jpg","contentUrl":"https:\/\/argest.lu\/wp-content\/uploads\/2024\/02\/argest.jpg","width":769,"height":945,"caption":"Argest"},"image":{"@id":"https:\/\/www.argest.lu\/de#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.argest.lu\/de#\/schema\/person\/8b7b6c7808b0df3e7c1da4e4c9ff509b","name":"hamitso","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/b0d2b34ed9cec25863f37f628f3780ef6de1b759e8dbbbd7c855ba95d576f3bd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b0d2b34ed9cec25863f37f628f3780ef6de1b759e8dbbbd7c855ba95d576f3bd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b0d2b34ed9cec25863f37f628f3780ef6de1b759e8dbbbd7c855ba95d576f3bd?s=96&d=mm&r=g","caption":"hamitso"},"sameAs":["https:"]}]}},"_links":{"self":[{"href":"https:\/\/argest.lu\/de\/wp-json\/wp\/v2\/posts\/2484","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/argest.lu\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/argest.lu\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/argest.lu\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/argest.lu\/de\/wp-json\/wp\/v2\/comments?post=2484"}],"version-history":[{"count":1,"href":"https:\/\/argest.lu\/de\/wp-json\/wp\/v2\/posts\/2484\/revisions"}],"predecessor-version":[{"id":2487,"href":"https:\/\/argest.lu\/de\/wp-json\/wp\/v2\/posts\/2484\/revisions\/2487"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/argest.lu\/de\/wp-json\/wp\/v2\/media\/1124"}],"wp:attachment":[{"href":"https:\/\/argest.lu\/de\/wp-json\/wp\/v2\/media?parent=2484"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/argest.lu\/de\/wp-json\/wp\/v2\/categories?post=2484"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/argest.lu\/de\/wp-json\/wp\/v2\/tags?post=2484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}